{"id":60,"count":23,"description":"","link":"https:\/\/www.affiliabet.com\/it\/category\/marketing-di-affiliazione\/","name":"Marketing di affiliazione","slug":"marketing-di-affiliazione","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.6.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Marketing di affiliazione archivos - Affiliabet<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marketing di affiliazione archivos - Affiliabet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.affiliabet.com\/it\/category\/marketing-di-affiliazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Affiliabet\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.affiliabet.com\/wp-content\/uploads\/2021\/04\/affiliabet_logo_juegoresponsable.png\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.affiliabet.com\/#organization\",\"name\":\"Affiliabet\",\"url\":\"https:\/\/www.affiliabet.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.affiliabet.com\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.affiliabet.com\/wp-content\/uploads\/2021\/01\/logo.jpg\",\"width\":387,\"height\":101,\"caption\":\"Affiliabet\"},\"image\":{\"@id\":\"https:\/\/www.affiliabet.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.affiliabet.com\/#website\",\"url\":\"https:\/\/www.affiliabet.com\/\",\"name\":\"Affiliabet\",\"description\":\"Gestor N\\u00ba1 en campa\\u00f1as de afiliaci\\u00f3n de apuestas deportivas y juego online\",\"publisher\":{\"@id\":\"https:\/\/www.affiliabet.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.affiliabet.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.affiliabet.com\/it\/category\/marketing-di-affiliazione\/#webpage\",\"url\":\"https:\/\/www.affiliabet.com\/it\/category\/marketing-di-affiliazione\/\",\"name\":\"Marketing di affiliazione archivos - Affiliabet\",\"isPartOf\":{\"@id\":\"https:\/\/www.affiliabet.com\/#website\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.affiliabet.com\/it\/category\/marketing-di-affiliazione\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.affiliabet.com\/it\/wp-json\/wp\/v2\/categories\/60"}],"collection":[{"href":"https:\/\/www.affiliabet.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.affiliabet.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.affiliabet.com\/it\/wp-json\/wp\/v2\/posts?categories=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}